{
    "id": 12571,
    "date": "2024-07-25T13:27:34",
    "date_gmt": "2024-07-25T12:27:34",
    "guid": {
        "rendered": "https:\/\/www.tireetrust.org.uk\/?page_id=12571"
    },
    "modified": "2026-04-14T13:21:42",
    "modified_gmt": "2026-04-14T12:21:42",
    "slug": "book-an-epc",
    "status": "publish",
    "type": "page",
    "link": "https:\/\/www.tireetrust.org.uk\/en\/book-an-epc\/",
    "title": {
        "rendered": "Book an EPC"
    },
    "content": {
        "rendered": "<div class=\"wp-block-group has-ti-fg-alt-background-color has-background eplus-wrapper is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40)\">\n<p class=\"eplus-wrapper\">We are STILL offering <strong>FREE EPCs to Tiree residents<\/strong>. These EPCs will help us learn about the Tiree housing stock, and give you data you can use when you are looking at ways to improve your energy efficiency! <a class=\"ek-link\" href=\"https:\/\/www.tireetrust.org.uk\/en\/help-us-improve-tirees-homes-free-epcs-available\/\">Find out more<\/a>.<\/p>\n<\/div>\n\n\n\n<p class=\"eplus-wrapper\">The Trust is able to offer Energy Performance Certificates. Pricing begins at \u00a3193.50 for members of the Trust and \u00a3215 for non-members. <\/p>\n\n\n\n<p class=\"eplus-wrapper\">Pricing for paid EPCs is based on the following market valuation banding. <\/p>\n\n\n\n<figure class=\"wp-block-table eplus-wrapper\"><table class=\"has-fixed-layout\"><tbody><tr><td><\/td><td><strong>NON-MEMBER FEE<\/strong><\/td><td><strong>MEMBER FEE<\/strong><\/td><\/tr><tr><td><strong>BAND 1<\/strong><br>&gt;\u00a3199,999<\/td><td>\u00a3215.00<\/td><td>\u00a3193.50<\/td><\/tr><tr><td><strong>BAND 2<br><\/strong>\u00a3200,000 &#8211; \u00a3349,999<\/td><td>\u00a3275.00<\/td><td>\u00a3247.50<\/td><\/tr><tr><td><strong>BAND 3<br><\/strong>\u00a3350,000 &#8211; \u00a3499,999<\/td><td>\u00a3340.00<\/td><td>\u00a3306.00<\/td><\/tr><tr><td><strong>BAND 4<br><\/strong>\u00a3500,000 &#8211; \u00a3749,999<\/td><td>\u00a3400.00<\/td><td>\u00a3360.00<\/td><\/tr><tr><td><strong>BAND 5<br><\/strong>\u00a3750,000+<\/td><td>\u00a3490.00<\/td><td>\u00a3441.00<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"eplus-wrapper\">If you would like to book an EPC please fill out the form below and a member of our team will be in touch.<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-abd08cb7-2fbb-4b0f-a1a1-9b076e60f7eb\" id=\"wpforms-12564\"><form id=\"wpforms-form-12564\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"12564\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/12571\" data-token=\"6d897f77a05b4a3cd33e738480382510\" data-token-time=\"1778685771\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/12571\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-12564-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-12564-field_2\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][2][first]\" required><label for=\"wpforms-12564-field_2\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-12564-field_2-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][2][last]\" required><label for=\"wpforms-12564-field_2-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-12564-field_11-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_11\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-12564-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-12564-field_12-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_12\">Phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-12564-field_12\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][12]\" aria-label=\"Phone\" required><\/div><div id=\"wpforms-12564-field_3-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"3\"><label class=\"wpforms-field-label\">Relationship to Property <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-12564-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-12564-field_3_1\" name=\"wpforms[fields][3]\" value=\"Homeowner\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_3_1\">Homeowner<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-12564-field_3_2\" name=\"wpforms[fields][3]\" value=\"Occupier\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_3_2\">Occupier<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-12564-field_3_3\" name=\"wpforms[fields][3]\" value=\"Estate Agent\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_3_3\">Estate Agent<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-12564-field_3_4\" name=\"wpforms[fields][3]\" value=\"Other (please specify below)\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_3_4\">Other (please specify below)<\/label><\/li><\/ul><\/div><div id=\"wpforms-12564-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_4\">Other: Relationship to Property<\/label><input type=\"text\" id=\"wpforms-12564-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" ><\/div><div id=\"wpforms-12564-field_1-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"1\"><label class=\"wpforms-field-label\">Property Details <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-description\">Please enter the details for the property requiring the EPC. <\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-12564-field_1\" class=\"wpforms-field-address-address1 wpforms-field-required\" name=\"wpforms[fields][1][address1]\" required><label for=\"wpforms-12564-field_1\" class=\"wpforms-field-sublabel after\">Address Line 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div ><input type=\"text\" id=\"wpforms-12564-field_1-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][1][address2]\" ><label for=\"wpforms-12564-field_1-address2\" class=\"wpforms-field-sublabel after\">Address Line 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-12564-field_1-city\" class=\"wpforms-field-address-city wpforms-field-required\" name=\"wpforms[fields][1][city]\" placeholder=\"Isle of Tiree\" required><label for=\"wpforms-12564-field_1-city\" class=\"wpforms-field-sublabel after\">City<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-12564-field_1-state\" class=\"wpforms-field-address-state wpforms-field-required\" name=\"wpforms[fields][1][state]\" value=\"Argyll\" required><label for=\"wpforms-12564-field_1-state\" class=\"wpforms-field-sublabel after\">State \/ Province \/ Region<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-12564-field_1-postal\" class=\"wpforms-field-address-postal wpforms-field-required\" name=\"wpforms[fields][1][postal]\" required><label for=\"wpforms-12564-field_1-postal\" class=\"wpforms-field-sublabel after\">Postal Code<\/label><\/div><\/div><\/div><div id=\"wpforms-12564-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_5\">Directions to Property<\/label><div class=\"wpforms-field-description\">If you think it would helpful, please provide either a What3Words reference or additional directions as to where your property is located. <\/div><textarea id=\"wpforms-12564-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" ><\/textarea><\/div><div id=\"wpforms-12564-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_6\">Market Valuation<\/label><div class=\"wpforms-field-description\">Please provide a recent market valuation, if available. If a recent market valuation is not available an estimate will be calculated. <\/div><input type=\"text\" id=\"wpforms-12564-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" ><\/div><div id=\"wpforms-12564-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_7\">Reason for Instructing an EPC <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-description\">Please provide a brief explanation as to why you require an EPC. \n\ne.g. marketed sale, non-marketed sale, rental etc. <\/div><textarea id=\"wpforms-12564-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" required><\/textarea><\/div><div id=\"wpforms-12564-field_8-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-12564-field_8\">Notable Property Features<\/label><div class=\"wpforms-field-description\">Please briefly describe any property features that are particularly unusual (if any). \n\ne.g. renewables, listed building status, or unusual construction. <\/div><textarea id=\"wpforms-12564-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" ><\/textarea><\/div><div id=\"wpforms-12564-field_9-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"9\"><label class=\"wpforms-field-label\">Are you a member of Urras Thiriodh? <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-description\">Members are eligible for a 10% member discount for their main residence and one additional property owned by their household. <\/div><ul id=\"wpforms-12564-field_9\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-12564-field_9_1\" name=\"wpforms[fields][9][]\" value=\"Yes\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_9_1\">Yes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-12564-field_9_4\" name=\"wpforms[fields][9][]\" value=\"No\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_9_4\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-12564-field_10-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"10\"><label class=\"wpforms-field-label\">Terms and Conditions: I agree to the Paid Energy Performance Certificate Service Terms and Conditions, and the associated Privacy Policy. <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-description\"><a href=\"\/en\/privacy-policy\/\">View Privacy Policy<\/a> | <a href=\"https:\/\/www.tireetrust.org.uk\/wp-content\/uploads\/2025\/05\/Terms-and-Conditions-for-Paid-Energy-Performance-Certificate-Service-Reviewed-May-2025.pdf\">Download Terms &amp; Conditions<\/a><\/div><ul id=\"wpforms-12564-field_10\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-12564-field_10_1\" name=\"wpforms[fields][10][]\" value=\"Yes\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-12564-field_10_1\">Yes<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"12564\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/pages\/12571\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-12564\" class=\"wpforms-submit\" data-alt-text=\"Sending\u2026\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tireetrust.org.uk\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div>  <!-- .wpforms-container -->",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>We are STILL offering FREE EPCs to Tiree residents. These EPCs will help us learn about the Tiree housing stock, and give you data you can use when you are looking at ways to improve your energy efficiency! Find out more. The Trust is able to offer Energy Performance Certificates. Pricing begins at \u00a3193.50 for [\u2026]<\/p>",
        "protected": false
    },
    "author": 2,
    "featured_media": 12414,
    "parent": 0,
    "menu_order": 0,
    "comment_status": "closed",
    "ping_status": "closed",
    "template": "",
    "meta": {
        "_editorskit_title_hidden": false,
        "_editorskit_reading_time": 0,
        "_editorskit_is_block_options_detached": false,
        "_editorskit_block_options_position": "{}",
        "editor_plus_copied_stylings": "{}",
        "jetpack_post_was_ever_published": false,
        "footnotes": ""
    },
    "class_list": [
        "post-12571",
        "page",
        "type-page",
        "status-publish",
        "has-post-thumbnail",
        "hentry"
    ],
    "jetpack_shortlink": "https:\/\/wp.me\/PfVRvl-3gL",
    "jetpack_sharing_enabled": true,
    "_links": {
        "self": [
            {
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/pages\/12571",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/pages"
            }
        ],
        "about": [
            {
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/types\/page"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/users\/2"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/comments?post=12571"
            }
        ],
        "version-history": [
            {
                "count": 13,
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/pages\/12571\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 14559,
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/pages\/12571\/revisions\/14559"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/media\/12414"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/www.tireetrust.org.uk\/en\/wp-json\/wp\/v2\/media?parent=12571"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}